{"id":7,"count":17,"description":"","link":"http:\/\/www.aichi-con.co.jp\/info\/item06\/","name":"\u4e00\u822c\u88fd\u54c1\u30fb\u305d\u306e\u4ed6","slug":"item06","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.aichi-con.co.jp\/info\/wp-json\/wp\/v2\/categories\/7"}],"collection":[{"href":"http:\/\/www.aichi-con.co.jp\/info\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.aichi-con.co.jp\/info\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.aichi-con.co.jp\/info\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}